{"id":1970,"date":"2013-03-31T08:44:28","date_gmt":"2013-03-31T06:44:28","guid":{"rendered":"https:\/\/recruit2.com\/nl\/?p=1970"},"modified":"2013-04-19T17:47:33","modified_gmt":"2013-04-19T15:47:33","slug":"7-tips-van-headhunters-om-endorsements-slim-te-gebruiken","status":"publish","type":"post","link":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/","title":{"rendered":"7 tips van headhunters om endorsements slim te gebruiken"},"content":{"rendered":"<p>Intermediair.nl is gestart met een nieuwe reeks van artikelen waarin een expertpanel van recruiters en headhunters gevraagd worden naar hun mening over een bepaald onderwerp.<\/p>\n<p>Het onderwerp van de eerste aflevering gaat over de zin en onzin van <em>LinkedIn Endorsements<\/em> die men sinds een halfjaar kan ontvangen voor bepaalde vaardigheden of ervaring. De vragen:<\/p>\n<ol>\n<li>Zijn endorsements belangrijk? Let je er op als recruiter?<\/li>\n<li>Of zijn \u2018recommendations\u2019 belangrijker?<\/li>\n<li>Heb je voorbeelden uit je praktijk waarbij endorsements of recommendations op LinkedIn doorslaggevend zijn geweest? Ten positieve?<\/li>\n<li>Ten negatieve?<\/li>\n<li>Is het als werkzoekende verstandig om mensen uit je netwerk te vragen of ze je willen endorsen?<\/li>\n<li>Aan wie moet je die vragen? Maakt het uit door wie je bent \u2018ge-endorst\u2019?<\/li>\n<li>Hoeveel endorsements heb je nodig per expertise-gebied?<\/li>\n<li>Hoe kies je de juiste expertise-gebieden?<\/li>\n<li>Waarom zou je anderen \u2018endorsen\u2019? En onder welke omstandigheden moet je dat doen?<\/li>\n<\/ol>\n<p>Kortom, hoe haal je het meeste uit <em>LinkedIn Endorsements<\/em>? Lees onze mening en die van andere collega&#8217;s in het online artikel <a href=\"http:\/\/www.intermediair.nl\/carriere\/doorgroeien\/competenties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\" target=\"_blank\">7 tips van headhunters om endorsements slim te gebruiken<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intermediair.nl is gestart met een nieuwe reeks van artikelen waarin een expertpanel van recruiters en headhunters gevraagd worden naar hun mening over een bepaald onderwerp. Het onderwerp van de eerste aflevering gaat over de zin en onzin van LinkedIn Endorsements die men sinds een halfjaar kan ontvangen voor bepaalde vaardigheden of ervaring. De vragen: Zijn [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[231,36,232],"class_list":["post-1970","post","type-post","status-publish","format-standard","hentry","category-pers-en-publicaties","tag-competenties","tag-social-media","tag-vaardigheden"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 tips van headhunters om endorsements slim te gebruiken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 tips van headhunters om endorsements slim te gebruiken\" \/>\n<meta property=\"og:description\" content=\"Intermediair.nl is gestart met een nieuwe reeks van artikelen waarin een expertpanel van recruiters en headhunters gevraagd worden naar hun mening over een bepaald onderwerp. Het onderwerp van de eerste aflevering gaat over de zin en onzin van LinkedIn Endorsements die men sinds een halfjaar kan ontvangen voor bepaalde vaardigheden of ervaring. De vragen: Zijn [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\" \/>\n<meta property=\"og:site_name\" content=\"Recruit2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/recruit2\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jaccov\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-31T06:44:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-19T15:47:33+00:00\" \/>\n<meta name=\"author\" content=\"Jacco Valkenburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/jaccov\" \/>\n<meta name=\"twitter:site\" content=\"@Recruit2HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacco Valkenburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\"},\"author\":{\"name\":\"Jacco Valkenburg\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7\"},\"headline\":\"7 tips van headhunters om endorsements slim te gebruiken\",\"datePublished\":\"2013-03-31T06:44:28+00:00\",\"dateModified\":\"2013-04-19T15:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\"},\"keywords\":[\"Competenties\",\"Social Media\",\"Vaardigheden\"],\"articleSection\":[\"Pers en publicaties\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\",\"url\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\",\"name\":\"7 tips van headhunters om endorsements slim te gebruiken\",\"isPartOf\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#website\"},\"datePublished\":\"2013-03-31T06:44:28+00:00\",\"dateModified\":\"2013-04-19T15:47:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recruit2.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competenties\",\"item\":\"https:\/\/recruit2.com\/nl\/tag\/competenties\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"7 tips van headhunters om endorsements slim te gebruiken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recruit2.com\/nl\/#website\",\"url\":\"https:\/\/recruit2.com\/nl\/\",\"name\":\"Recruit2\",\"description\":\"AI Recruitment Specialist\",\"publisher\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recruit2.com\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\",\"name\":\"Recruit2\",\"url\":\"https:\/\/recruit2.com\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg\",\"contentUrl\":\"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg\",\"width\":\"530\",\"height\":\"260\",\"caption\":\"Recruit2\"},\"image\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/recruit2\",\"https:\/\/x.com\/Recruit2HQ\",\"https:\/\/www.linkedin.com\/company\/recruit2\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7\",\"name\":\"Jacco Valkenburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g\",\"caption\":\"Jacco Valkenburg\"},\"description\":\"Jacco Valkenburg is AI Recruitment Expert, LinkedIn specialist en oprichter van Recruit2. Hij schreef bestsellers als Recruitment 4.0 en traint recruiters wereldwijd in AI, LinkedIn en neuromarketing.\",\"sameAs\":[\"https:\/\/recruit2.com\/contact\/jacco-valkenburg\/\",\"https:\/\/www.facebook.com\/jaccov\",\"https:\/\/www.linkedin.com\/in\/jacco\",\"https:\/\/x.com\/https:\/\/x.com\/jaccov\",\"https:\/\/www.youtube.com\/user\/IPRC\"],\"url\":\"https:\/\/recruit2.com\/nl\/author\/jacco-valkenburg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 tips van headhunters om endorsements slim te gebruiken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/","og_locale":"nl_NL","og_type":"article","og_title":"7 tips van headhunters om endorsements slim te gebruiken","og_description":"Intermediair.nl is gestart met een nieuwe reeks van artikelen waarin een expertpanel van recruiters en headhunters gevraagd worden naar hun mening over een bepaald onderwerp. Het onderwerp van de eerste aflevering gaat over de zin en onzin van LinkedIn Endorsements die men sinds een halfjaar kan ontvangen voor bepaalde vaardigheden of ervaring. De vragen: Zijn [&hellip;]","og_url":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/","og_site_name":"Recruit2","article_publisher":"https:\/\/www.facebook.com\/recruit2","article_author":"https:\/\/www.facebook.com\/jaccov","article_published_time":"2013-03-31T06:44:28+00:00","article_modified_time":"2013-04-19T15:47:33+00:00","author":"Jacco Valkenburg","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/jaccov","twitter_site":"@Recruit2HQ","twitter_misc":{"Geschreven door":"Jacco Valkenburg","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#article","isPartOf":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/"},"author":{"name":"Jacco Valkenburg","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7"},"headline":"7 tips van headhunters om endorsements slim te gebruiken","datePublished":"2013-03-31T06:44:28+00:00","dateModified":"2013-04-19T15:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/recruit2.com\/nl\/#organization"},"keywords":["Competenties","Social Media","Vaardigheden"],"articleSection":["Pers en publicaties"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/","url":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/","name":"7 tips van headhunters om endorsements slim te gebruiken","isPartOf":{"@id":"https:\/\/recruit2.com\/nl\/#website"},"datePublished":"2013-03-31T06:44:28+00:00","dateModified":"2013-04-19T15:47:33+00:00","breadcrumb":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/7-tips-van-headhunters-om-endorsements-slim-te-gebruiken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recruit2.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Competenties","item":"https:\/\/recruit2.com\/nl\/tag\/competenties\/"},{"@type":"ListItem","position":3,"name":"7 tips van headhunters om endorsements slim te gebruiken"}]},{"@type":"WebSite","@id":"https:\/\/recruit2.com\/nl\/#website","url":"https:\/\/recruit2.com\/nl\/","name":"Recruit2","description":"AI Recruitment Specialist","publisher":{"@id":"https:\/\/recruit2.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recruit2.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/recruit2.com\/nl\/#organization","name":"Recruit2","url":"https:\/\/recruit2.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg","contentUrl":"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg","width":"530","height":"260","caption":"Recruit2"},"image":{"@id":"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/recruit2","https:\/\/x.com\/Recruit2HQ","https:\/\/www.linkedin.com\/company\/recruit2"]},{"@type":"Person","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7","name":"Jacco Valkenburg","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g","caption":"Jacco Valkenburg"},"description":"Jacco Valkenburg is AI Recruitment Expert, LinkedIn specialist en oprichter van Recruit2. Hij schreef bestsellers als Recruitment 4.0 en traint recruiters wereldwijd in AI, LinkedIn en neuromarketing.","sameAs":["https:\/\/recruit2.com\/contact\/jacco-valkenburg\/","https:\/\/www.facebook.com\/jaccov","https:\/\/www.linkedin.com\/in\/jacco","https:\/\/x.com\/https:\/\/x.com\/jaccov","https:\/\/www.youtube.com\/user\/IPRC"],"url":"https:\/\/recruit2.com\/nl\/author\/jacco-valkenburg\/"}]}},"_links":{"self":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts\/1970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/comments?post=1970"}],"version-history":[{"count":0,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts\/1970\/revisions"}],"wp:attachment":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/media?parent=1970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/categories?post=1970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/tags?post=1970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}