{"id":3151,"date":"2015-05-24T08:00:09","date_gmt":"2015-05-24T06:00:09","guid":{"rendered":"https:\/\/recruit2.com\/nl\/?p=3151"},"modified":"2015-05-23T00:14:12","modified_gmt":"2015-05-22T22:14:12","slug":"afwijzingen-na-sollicitatie","status":"publish","type":"post","link":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/","title":{"rendered":"Hoe blijf je enthousiast, ondanks een reeks afwijzingen na sollicitatie?"},"content":{"rendered":"<p><strong>Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. <a href=\"http:\/\/www.intermediair.nl\/carriere\/cv-en-sollicitatie\/sollicitatiegesprek\/9-manieren-om-sollicitatiemoeheid-te-bestrijden\" target=\"_blank\">Intermediair.nl<\/a> vroeg 5 headhunters om hun beste adviezen.<\/strong><\/p>\n<p>Interim recruiter en adviseur Jacco Valkenburg van Recruit2 hierover. \u2018Iemand die sollicitatiemoe is mist vaak focus, is niet arbeidsmarktklaar, of straalt niet het vertrouwen uit dat hij of zij de juiste persoon is om de klus te klaren.\u2019<\/p>\n<p>Wanneer er honderden reacties zijn op een baan, hoe kun je dan in hemelsnaam toch een kans maken? Jacco Valkenburg: \u2018<a href=\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/hoe-vind-ik-een-baan-zonder-te-solliciteren\/\">Netwerk naar een baan<\/a> in plaats van alleen snel te reageren op openbaar gepubliceerde banen op vacaturesites. Het is veel effectiever om aan een bedrijf voorgesteld te worden dankzij een aanbeveling uit je persoonlijke netwerk. Om zover te komen, zul je tijd moeten investeren. Verdiep je daadwerkelijk in bedrijven en functies. Doe veel desk- en fieldresearch. Bovendien is focus, focus en nog eens focus essentieel.\u2019<\/p>\n<h2>9 manieren om sollicitatiemoeheid te bestrijden<\/h2>\n<ol>\n<li>Onderschat het negatieve effect van sollicitatiemoeheid niet<\/li>\n<li>Stel realistische doelen<\/li>\n<li>Wijt de situatie niet aan externe factoren<\/li>\n<li>Vraag expliciet om feedback<\/li>\n<li>Wees vacatures voor<\/li>\n<li>Solliciteer minder<\/li>\n<li>Kies met je hart<\/li>\n<li>Leg contact<\/li>\n<li>Laat het verleden los<\/li>\n<\/ol>\n<p>Het is belangrijk dat de werkgever een gevoel krijgt \u201cdie wil ik spreken\u201d omdat deze verwacht dat jij kan helpen met hun probleem. Dat vraagt om verdieping in het bedrijf en\/of functie. Doe dus veel desk- en fieldresearch en netwerk naar een baan in plaats van alleen snel te reageren op openbaar gepubliceerde banen op vacaturesites. Dat kost tijd en daarvoor is focus, focus en nog eens focus essentieel. Standaard sollicitaties, smeekbrieven, of in brieven \/ interviews vermelden dat je weinig relevante ervaring hebt, helpen niet om het (zelf)vertrouwen en de gunfactor te vergroten.<\/p>\n<p>Meer hierover lezen? Lees het volledige artikel op <a href=\"http:\/\/www.intermediair.nl\/carriere\/cv-en-sollicitatie\/sollicitatiegesprek\/9-manieren-om-sollicitatiemoeheid-te-bestrijden\" target=\"_blank\">Intermediair.nl<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[33,103],"class_list":["post-3151","post","type-post","status-publish","format-standard","hentry","category-pers-en-publicaties","tag-intermediair","tag-sollicitatie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?<\/title>\n<meta name=\"description\" content=\"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?\" \/>\n<meta property=\"og:description\" content=\"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Recruit2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/recruit2\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jaccov\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-24T06:00:09+00:00\" \/>\n<meta name=\"author\" content=\"Jacco Valkenburg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/jaccov\" \/>\n<meta name=\"twitter:site\" content=\"@Recruit2HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacco Valkenburg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\"},\"author\":{\"name\":\"Jacco Valkenburg\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7\"},\"headline\":\"Hoe blijf je enthousiast, ondanks een reeks afwijzingen na sollicitatie?\",\"datePublished\":\"2015-05-24T06:00:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\"},\"wordCount\":308,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\"},\"keywords\":[\"Intermediair\",\"Sollicitatie\"],\"articleSection\":[\"Pers en publicaties\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\",\"url\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\",\"name\":\"Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?\",\"isPartOf\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#website\"},\"datePublished\":\"2015-05-24T06:00:09+00:00\",\"description\":\"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.\",\"breadcrumb\":{\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recruit2.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intermediair\",\"item\":\"https:\/\/recruit2.com\/nl\/tag\/intermediair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hoe blijf je enthousiast, ondanks een reeks afwijzingen na sollicitatie?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recruit2.com\/nl\/#website\",\"url\":\"https:\/\/recruit2.com\/nl\/\",\"name\":\"Recruit2\",\"description\":\"AI Recruitment Specialist\",\"publisher\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recruit2.com\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/recruit2.com\/nl\/#organization\",\"name\":\"Recruit2\",\"url\":\"https:\/\/recruit2.com\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg\",\"contentUrl\":\"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg\",\"width\":\"530\",\"height\":\"260\",\"caption\":\"Recruit2\"},\"image\":{\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/recruit2\",\"https:\/\/x.com\/Recruit2HQ\",\"https:\/\/www.linkedin.com\/company\/recruit2\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7\",\"name\":\"Jacco Valkenburg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/recruit2.com\/nl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g\",\"caption\":\"Jacco Valkenburg\"},\"description\":\"Jacco Valkenburg is AI Recruitment Expert, LinkedIn specialist en oprichter van Recruit2. Hij schreef bestsellers als Recruitment 4.0 en traint recruiters wereldwijd in AI, LinkedIn en neuromarketing.\",\"sameAs\":[\"https:\/\/recruit2.com\/contact\/jacco-valkenburg\/\",\"https:\/\/www.facebook.com\/jaccov\",\"https:\/\/www.linkedin.com\/in\/jacco\",\"https:\/\/x.com\/https:\/\/x.com\/jaccov\",\"https:\/\/www.youtube.com\/user\/IPRC\"],\"url\":\"https:\/\/recruit2.com\/nl\/author\/jacco-valkenburg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?","description":"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/","og_locale":"nl_NL","og_type":"article","og_title":"Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?","og_description":"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.","og_url":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/","og_site_name":"Recruit2","article_publisher":"https:\/\/www.facebook.com\/recruit2","article_author":"https:\/\/www.facebook.com\/jaccov","article_published_time":"2015-05-24T06:00:09+00:00","author":"Jacco Valkenburg","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/jaccov","twitter_site":"@Recruit2HQ","twitter_misc":{"Geschreven door":"Jacco Valkenburg","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#article","isPartOf":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/"},"author":{"name":"Jacco Valkenburg","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7"},"headline":"Hoe blijf je enthousiast, ondanks een reeks afwijzingen na sollicitatie?","datePublished":"2015-05-24T06:00:09+00:00","mainEntityOfPage":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/"},"wordCount":308,"commentCount":0,"publisher":{"@id":"https:\/\/recruit2.com\/nl\/#organization"},"keywords":["Intermediair","Sollicitatie"],"articleSection":["Pers en publicaties"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/","url":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/","name":"Hoe blijf je enthousiast, ondanks afwijzingen na sollicitatie?","isPartOf":{"@id":"https:\/\/recruit2.com\/nl\/#website"},"datePublished":"2015-05-24T06:00:09+00:00","description":"Wanneer je al wat langer solliciteert, kan het een hele kunst zijn om toch de moed er in te blijven houden. 9 manieren om sollicitatiemoeheid te bestrijden.","breadcrumb":{"@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recruit2.com\/nl\/pers-en-publicaties\/afwijzingen-na-sollicitatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recruit2.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Intermediair","item":"https:\/\/recruit2.com\/nl\/tag\/intermediair\/"},{"@type":"ListItem","position":3,"name":"Hoe blijf je enthousiast, ondanks een reeks afwijzingen na sollicitatie?"}]},{"@type":"WebSite","@id":"https:\/\/recruit2.com\/nl\/#website","url":"https:\/\/recruit2.com\/nl\/","name":"Recruit2","description":"AI Recruitment Specialist","publisher":{"@id":"https:\/\/recruit2.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recruit2.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/recruit2.com\/nl\/#organization","name":"Recruit2","url":"https:\/\/recruit2.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg","contentUrl":"https:\/\/recruit2.com\/nl\/files\/2010\/10\/recruit2-logo.jpg","width":"530","height":"260","caption":"Recruit2"},"image":{"@id":"https:\/\/recruit2.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/recruit2","https:\/\/x.com\/Recruit2HQ","https:\/\/www.linkedin.com\/company\/recruit2"]},{"@type":"Person","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/96e9cc39711e1c6e0b478d6c7ad602e7","name":"Jacco Valkenburg","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/recruit2.com\/nl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/163436cffd327815cbce9a0716f2eb95?s=96&d=blank&r=g","caption":"Jacco Valkenburg"},"description":"Jacco Valkenburg is AI Recruitment Expert, LinkedIn specialist en oprichter van Recruit2. Hij schreef bestsellers als Recruitment 4.0 en traint recruiters wereldwijd in AI, LinkedIn en neuromarketing.","sameAs":["https:\/\/recruit2.com\/contact\/jacco-valkenburg\/","https:\/\/www.facebook.com\/jaccov","https:\/\/www.linkedin.com\/in\/jacco","https:\/\/x.com\/https:\/\/x.com\/jaccov","https:\/\/www.youtube.com\/user\/IPRC"],"url":"https:\/\/recruit2.com\/nl\/author\/jacco-valkenburg\/"}]}},"_links":{"self":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":0,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"wp:attachment":[{"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recruit2.com\/nl\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}